{"id":22426,"date":"2018-07-17T15:31:28","date_gmt":"2018-07-17T15:31:28","guid":{"rendered":"http:\/\/www.confenar.com.br\/?post_type=revistas&#038;p=22426"},"modified":"2018-10-09T20:05:25","modified_gmt":"2018-10-09T20:05:25","slug":"82-diferenciais-do-bom-vendedor","status":"publish","type":"revistas","link":"https:\/\/www.confenar.com.br\/index.php\/revistas\/82-diferenciais-do-bom-vendedor\/","title":{"rendered":"Diferenciais do Bom Vendedor"},"content":{"rendered":"<p class=\"p1\">Revendas e especialistas citam a import\u00e2ncia do relacionamento com os clientes<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-22426","revistas","type-revistas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.confenar.com.br\/index.php\/wp-json\/wp\/v2\/revistas\/22426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.confenar.com.br\/index.php\/wp-json\/wp\/v2\/revistas"}],"about":[{"href":"https:\/\/www.confenar.com.br\/index.php\/wp-json\/wp\/v2\/types\/revistas"}],"wp:attachment":[{"href":"https:\/\/www.confenar.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=22426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}